{"id":1315,"date":"2024-07-16T16:16:48","date_gmt":"2024-07-16T14:16:48","guid":{"rendered":"https:\/\/argonneboisenergie.com\/?page_id=1315"},"modified":"2024-08-01T12:30:20","modified_gmt":"2024-08-01T10:30:20","slug":"a-propos","status":"publish","type":"page","link":"https:\/\/argonneboisenergie.com\/index.php\/a-propos\/","title":{"rendered":"\u00c0\u00a0propos"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1315\" class=\"elementor elementor-1315\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-224b9b6 elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"224b9b6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;tilt&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d0f980b\" data-id=\"d0f980b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9bd7006 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"9bd7006\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-13d4e8b\" data-id=\"13d4e8b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04df591 elementor-nav-menu__align-end elementor-nav-menu--dropdown-mobile elementor-nav-menu--stretch elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"04df591\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;fa-svg-chevron-down e-font-icon-svg e-fas-chevron-down\\&quot; viewBox=\\&quot;0 0 448 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;full_width&quot;:&quot;stretch&quot;,&quot;toggle_icon_hover_animation&quot;:&quot;pop&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-04df591\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-732\"><a href=\"https:\/\/argonneboisenergie.com\/index.php\/about-us\/\" class=\"elementor-item\">Qui sommes-nous ?<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1317\"><a href=\"https:\/\/argonneboisenergie.com\/index.php\/a-propos\/\" class=\"elementor-sub-item\">\u00c0\u00a0propos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-936\"><a href=\"https:\/\/argonneboisenergie.com\/index.php\/notre-histoire\/\" class=\"elementor-sub-item\">Notre histoire<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-823\"><a href=\"https:\/\/argonneboisenergie.com\/index.php\/filieres-partenaires\/\" class=\"elementor-item\">Fili\u00e8re bois \u00e9nergie<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-825\"><a href=\"https:\/\/argonneboisenergie.com\/index.php\/contact\/\" class=\"elementor-item\">Contact<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Permuter le menu\" aria-expanded=\"false\">\n\t\t\t<svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open elementor-animation-pop e-font-icon-svg e-eicon-menu-bar\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M104 333H896C929 333 958 304 958 271S929 208 896 208H104C71 208 42 237 42 271S71 333 104 333ZM104 583H896C929 583 958 554 958 521S929 458 896 458H104C71 458 42 487 42 521S71 583 104 583ZM104 833H896C929 833 958 804 958 771S929 708 896 708H104C71 708 42 737 42 771S71 833 104 833Z\"><\/path><\/svg><svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close elementor-animation-pop e-font-icon-svg e-eicon-close\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M742 167L500 408 258 167C246 154 233 150 217 150 196 150 179 158 167 167 154 179 150 196 150 212 150 229 154 242 171 254L408 500 167 742C138 771 138 800 167 829 196 858 225 858 254 829L496 587 738 829C750 842 767 846 783 846 800 846 817 842 829 829 842 817 846 804 846 783 846 767 842 750 829 737L588 500 833 258C863 229 863 200 833 171 804 137 775 137 742 167Z\"><\/path><\/svg>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-04df591\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-732\"><a href=\"https:\/\/argonneboisenergie.com\/index.php\/about-us\/\" class=\"elementor-item\" tabindex=\"-1\">Qui sommes-nous ?<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1317\"><a href=\"https:\/\/argonneboisenergie.com\/index.php\/a-propos\/\" class=\"elementor-sub-item\" tabindex=\"-1\">\u00c0\u00a0propos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-936\"><a href=\"https:\/\/argonneboisenergie.com\/index.php\/notre-histoire\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Notre histoire<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-823\"><a href=\"https:\/\/argonneboisenergie.com\/index.php\/filieres-partenaires\/\" class=\"elementor-item\" tabindex=\"-1\">Fili\u00e8re bois \u00e9nergie<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-825\"><a href=\"https:\/\/argonneboisenergie.com\/index.php\/contact\/\" class=\"elementor-item\" tabindex=\"-1\">Contact<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a842eb elementor-widget elementor-widget-heading\" data-id=\"4a842eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">QUI SOMMES-NOUS ?<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9a8bc7c elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"9a8bc7c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-600fc55 animated-slow elementor-invisible\" data-id=\"600fc55\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6da43f9 elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6da43f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1694963 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"1694963\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Notre \u00e9quipe \u00e0 votre service !<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76e2d41 elementor-widget elementor-widget-heading\" data-id=\"76e2d41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tourn\u00e9e vers l'avenir et eco-responsable...<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbb89d1 elementor-widget elementor-widget-text-editor\" data-id=\"dbb89d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous sommes engag\u00e9s dans deux r\u00e9f\u00e9rentiels de qualit\u00e9, PEFC et Red II. Ceci est gage de bonnes pratiques d\u2019exploitations foresti\u00e8res et de tra\u00e7abilit\u00e9 de la biomasse.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47ef404 elementor-widget elementor-widget-button\" data-id=\"47ef404\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"mailto:contact@argonneboiseneregie.com\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-right-arrow\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Nous contacter <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b16bf7b\" data-id=\"b16bf7b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6bf83b elementor-widget elementor-widget-image\" data-id=\"b6bf83b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"960\" height=\"640\" src=\"https:\/\/argonneboisenergie.com\/wp-content\/uploads\/2024\/07\/biomasse-WD-ABE.png\" class=\"attachment-full size-full wp-image-1210\" alt=\"\" srcset=\"https:\/\/argonneboisenergie.com\/wp-content\/uploads\/2024\/07\/biomasse-WD-ABE.png 960w, https:\/\/argonneboisenergie.com\/wp-content\/uploads\/2024\/07\/biomasse-WD-ABE-300x200.png 300w, https:\/\/argonneboisenergie.com\/wp-content\/uploads\/2024\/07\/biomasse-WD-ABE-768x512.png 768w, https:\/\/argonneboisenergie.com\/wp-content\/uploads\/2024\/07\/biomasse-WD-ABE-600x400.png 600w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5bbc835 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5bbc835\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;tilt&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ac8d11\" data-id=\"4ac8d11\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-672447a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"672447a9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-276b3f0e\" data-id=\"276b3f0e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04db625 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"04db625\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LES Missions du technicien\/acheteur bois<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-67d4711 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"67d4711\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d187fa3\" data-id=\"d187fa3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9634369 elementor-hidden-tablet elementor-hidden-mobile elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9634369\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-money\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">APPROVISIONNEMENT \/ ACHATS<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3d14be elementor-hidden-desktop elementor-hidden-tablet elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c3d14be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-money\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">APPROVISIONNEMENT ACHATS<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da028bd elementor-widget elementor-widget-text-editor\" data-id=\"da028bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Sa mission est d&rsquo;approvisionner en bois la coop\u00e9rative.<\/li><li>Cela passe par des sollicitations par appels d&rsquo;offres, publics et priv\u00e9s (ONF, coop\u00e9ratives foresti\u00e8res, groupements forestiers, experts, gestionnaires priv\u00e9s, exploitants forestiers&#8230;) ainsi que par de la prospection de parcelles priv\u00e9es.\u00a0\u00a0<\/li><li>C&rsquo;est lui qui \u00e9value les volumes et la qualit\u00e9 des bois afin de n\u00e9gocier des prix d&rsquo;achats ou de participer aux ventes aux ench\u00e8res.\u00a0<\/li><li>Sa zone d&rsquo;approvisionnement couvre une partie du Grand-Est.\u00a0<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-158f0f6\" data-id=\"158f0f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d8b0e1 elementor-widget elementor-widget-spacer\" data-id=\"4d8b0e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f2dcf0 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1f2dcf0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tree\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M378.31 378.49L298.42 288h30.63c9.01 0 16.98-5 20.78-13.06 3.8-8.04 2.55-17.26-3.28-24.05L268.42 160h28.89c9.1 0 17.3-5.35 20.86-13.61 3.52-8.13 1.86-17.59-4.24-24.08L203.66 4.83c-6.03-6.45-17.28-6.45-23.32 0L70.06 122.31c-6.1 6.49-7.75 15.95-4.24 24.08C69.38 154.65 77.59 160 86.69 160h28.89l-78.14 90.91c-5.81 6.78-7.06 15.99-3.27 24.04C37.97 283 45.93 288 54.95 288h30.63L5.69 378.49c-6 6.79-7.36 16.09-3.56 24.26 3.75 8.05 12 13.25 21.01 13.25H160v24.45l-30.29 48.4c-5.32 10.64 2.42 23.16 14.31 23.16h95.96c11.89 0 19.63-12.52 14.31-23.16L224 440.45V416h136.86c9.01 0 17.26-5.2 21.01-13.25 3.8-8.17 2.44-17.47-3.56-24.26z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">EXPLOITATION<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8cd3627 elementor-widget elementor-widget-text-editor\" data-id=\"8cd3627\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Notre technicien lance et dirige les op\u00e9rations d&rsquo;abattage (manuelles ou m\u00e9canis\u00e9es) et le d\u00e9bardage des bois.\u00a0<\/li><li>Il supervise les chantiers d&rsquo;exploitations afin de s&rsquo;assurer du bon d\u00e9roulement de ceux-ci, aussi bien sur la technicit\u00e9 et la qualit\u00e9 de la r\u00e9alisation des travaux que sur le respect de la biodiversit\u00e9, des sols et des cours d&rsquo;eaux en phase avec la gestion durable de la for\u00eat (PEFC&#8230;)<\/li><li>Le suivi des chantiers lui permet \u00e9galement d&rsquo;ajuster au mieux la valorisation des diff\u00e9rents produits exploit\u00e9s (bois d&rsquo;\u0153uvre, bois d&rsquo;industrie, bois \u00e9nergie).<\/li><li>Plusieurs machines\/outils sont donc souvent n\u00e9cessaires \u00e0 l&rsquo;exploitation d&rsquo;un chantier.\u00a0<\/li><li>Il d\u00e9finit des zones de stockage pour les bois d&rsquo;\u0153uvre afin de pouvoir r\u00e9ceptionner et pr\u00e9parer les bois (cubage des grumes, d\u00e9coupes, valorisation des diff\u00e9rentes qualit\u00e9s) ainsi que des zones de stockage pour le bois d&rsquo;industrie \/ bois \u00e9nergie.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-95ffa6c elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"95ffa6c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6380610\" data-id=\"6380610\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eb8e78b elementor-widget elementor-widget-spacer\" data-id=\"eb8e78b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af747a7 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"af747a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-truck\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M624 352h-16V243.9c0-12.7-5.1-24.9-14.1-33.9L494 110.1c-9-9-21.2-14.1-33.9-14.1H416V48c0-26.5-21.5-48-48-48H48C21.5 0 0 21.5 0 48v320c0 26.5 21.5 48 48 48h16c0 53 43 96 96 96s96-43 96-96h128c0 53 43 96 96 96s96-43 96-96h48c8.8 0 16-7.2 16-16v-32c0-8.8-7.2-16-16-16zM160 464c-26.5 0-48-21.5-48-48s21.5-48 48-48 48 21.5 48 48-21.5 48-48 48zm320 0c-26.5 0-48-21.5-48-48s21.5-48 48-48 48 21.5 48 48-21.5 48-48 48zm80-208H416V144h44.1l99.9 99.9V256z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">    TRANSPORT<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8cf29f3 elementor-widget elementor-widget-text-editor\" data-id=\"8cf29f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Il planifie les chargements des grumes pour les acheminer vers leurs clients partenaires.\u00a0<\/li><li>Il estime les piles de bois \u00e9nergie pour ajuster au mieux la programmation du broyage et de la logistique.\u00a0<\/li><li>Selon la demande\u00a0de ses clients, l&rsquo;accessibilit\u00e9 des chantiers ainsi que ses engagements, le technicien programme le broyage des piles de bois \u00e9nergie et le transport des plaquettes foresti\u00e8res vers les sites clients.\u00a0<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7cda7fd\" data-id=\"7cda7fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c6591cf elementor-widget elementor-widget-spacer\" data-id=\"c6591cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d19e303 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d19e303\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-book-open\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M542.22 32.05c-54.8 3.11-163.72 14.43-230.96 55.59-4.64 2.84-7.27 7.89-7.27 13.17v363.87c0 11.55 12.63 18.85 23.28 13.49 69.18-34.82 169.23-44.32 218.7-46.92 16.89-.89 30.02-14.43 30.02-30.66V62.75c.01-17.71-15.35-31.74-33.77-30.7zM264.73 87.64C197.5 46.48 88.58 35.17 33.78 32.05 15.36 31.01 0 45.04 0 62.75V400.6c0 16.24 13.13 29.78 30.02 30.66 49.49 2.6 149.59 12.11 218.77 46.95 10.62 5.35 23.21-1.94 23.21-13.46V100.63c0-5.29-2.62-10.14-7.27-12.99z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R\u00c9CEPTION CHANTIER<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f4f421 elementor-widget elementor-widget-text-editor\" data-id=\"7f4f421\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Une fois termin\u00e9s, il s&rsquo;assure de la propret\u00e9 du rendu des chantiers et de la remise en \u00e9tat quand celle-ci s&rsquo;av\u00e8re n\u00e9cessaire.\u00a0<\/li><li>Lors de vente de bois \u00e0 l&rsquo;unit\u00e9 de produit, il recueille les \u00e9l\u00e9ments n\u00e9cessaires (cubage, tonnage&#8230;) afin de les transmettre au vendeur pour finaliser le paiement des produits.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cad5c1b elementor-absolute elementor-widget__width-auto elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2cad5c1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateX_effect&quot;:&quot;yes&quot;,&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_translateX_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateX_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2.3,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300,&quot;motion_fx_translateX_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SUR LE TERRAIN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-9a377ad e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"9a377ad\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-30d403a e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"30d403a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57d6668 elementor-widget elementor-widget-image\" data-id=\"57d6668\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"640\" src=\"https:\/\/argonneboisenergie.com\/wp-content\/uploads\/2024\/04\/2-1.png\" class=\"attachment-full size-full wp-image-913\" alt=\"\" srcset=\"https:\/\/argonneboisenergie.com\/wp-content\/uploads\/2024\/04\/2-1.png 960w, https:\/\/argonneboisenergie.com\/wp-content\/uploads\/2024\/04\/2-1-300x200.png 300w, https:\/\/argonneboisenergie.com\/wp-content\/uploads\/2024\/04\/2-1-768x512.png 768w, https:\/\/argonneboisenergie.com\/wp-content\/uploads\/2024\/04\/2-1-600x400.png 600w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fd51fe2 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"fd51fe2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71a97e2 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"71a97e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"mailto:contact@argonneboisenergie.com\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-right-arrow\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Int\u00e9r\u00e9ss\u00e9 pour vendre votre bois ? <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>QUI SOMMES-NOUS ? Notre \u00e9quipe \u00e0 votre service ! Tourn\u00e9e vers l&rsquo;avenir et eco-responsable&#8230; Nous sommes engag\u00e9s dans deux r\u00e9f\u00e9rentiels de qualit\u00e9, PEFC et Red II. Ceci est gage de bonnes pratiques d\u2019exploitations foresti\u00e8res et de tra\u00e7abilit\u00e9 de la biomasse. Nous contacter LES Missions du technicien\/acheteur bois APPROVISIONNEMENT \/ ACHATS APPROVISIONNEMENT ACHATS Sa mission est d&rsquo;approvisionner en bois la coop\u00e9rative. Cela passe par des sollicitations par appels d&rsquo;offres, publics et priv\u00e9s (ONF, coop\u00e9ratives foresti\u00e8res, groupements forestiers, experts, gestionnaires priv\u00e9s, exploitants forestiers&#8230;) ainsi que par de la prospection de parcelles priv\u00e9es.\u00a0\u00a0 C&rsquo;est lui qui \u00e9value les volumes et la qualit\u00e9 des bois afin de n\u00e9gocier des prix d&rsquo;achats ou de participer aux ventes aux ench\u00e8res.\u00a0 Sa zone d&rsquo;approvisionnement couvre&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-1315","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c0\u00a0propos - Argonne Bois Energie<\/title>\n<meta name=\"description\" content=\"le r\u00f4le d&#039;Argonne Bois \u00c9nergie est de rechercher les espaces bois\u00e9s locaux \u00e0 entretenir dans un futur proche, r\u00e9pondre \u00e0 cette offre et les transformer en bordure de parcelles ou sur nos plateformes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/argonneboisenergie.com\/index.php\/a-propos\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c0\u00a0propos - Argonne Bois Energie\" \/>\n<meta property=\"og:description\" content=\"le r\u00f4le d&#039;Argonne Bois \u00c9nergie est de rechercher les espaces bois\u00e9s locaux \u00e0 entretenir dans un futur proche, r\u00e9pondre \u00e0 cette offre et les transformer en bordure de parcelles ou sur nos plateformes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/argonneboisenergie.com\/index.php\/a-propos\/\" \/>\n<meta property=\"og:site_name\" content=\"Argonne Bois Energie\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-01T10:30:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/argonneboisenergie.com\/wp-content\/uploads\/2024\/07\/biomasse-WD-ABE.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/argonneboisenergie.com\\\/index.php\\\/a-propos\\\/\",\"url\":\"https:\\\/\\\/argonneboisenergie.com\\\/index.php\\\/a-propos\\\/\",\"name\":\"\u00c0\u00a0propos - Argonne Bois Energie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/argonneboisenergie.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/argonneboisenergie.com\\\/index.php\\\/a-propos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/argonneboisenergie.com\\\/index.php\\\/a-propos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/argonneboisenergie.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/biomasse-WD-ABE.png\",\"datePublished\":\"2024-07-16T14:16:48+00:00\",\"dateModified\":\"2024-08-01T10:30:20+00:00\",\"description\":\"le r\u00f4le d'Argonne Bois \u00c9nergie est de rechercher les espaces bois\u00e9s locaux \u00e0 entretenir dans un futur proche, r\u00e9pondre \u00e0 cette offre et les transformer en bordure de parcelles ou sur nos plateformes\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/argonneboisenergie.com\\\/index.php\\\/a-propos\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/argonneboisenergie.com\\\/index.php\\\/a-propos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/argonneboisenergie.com\\\/index.php\\\/a-propos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/argonneboisenergie.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/biomasse-WD-ABE.png\",\"contentUrl\":\"https:\\\/\\\/argonneboisenergie.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/biomasse-WD-ABE.png\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/argonneboisenergie.com\\\/index.php\\\/a-propos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/argonneboisenergie.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c0\u00a0propos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/argonneboisenergie.com\\\/#website\",\"url\":\"https:\\\/\\\/argonneboisenergie.com\\\/\",\"name\":\"Argonne Bois Energie\",\"description\":\"LES SP\u00c9CIALISTES DU BOIS \u00c9NERGIE EN CIRCUIT COURT !\",\"publisher\":{\"@id\":\"https:\\\/\\\/argonneboisenergie.com\\\/#organization\"},\"alternateName\":\"ABE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/argonneboisenergie.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/argonneboisenergie.com\\\/#organization\",\"name\":\"Argonne Bois Energie\",\"url\":\"https:\\\/\\\/argonneboisenergie.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/argonneboisenergie.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/argonneboisenergie.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/titre-ABE-2.png\",\"contentUrl\":\"https:\\\/\\\/argonneboisenergie.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/titre-ABE-2.png\",\"width\":250,\"height\":127,\"caption\":\"Argonne Bois Energie\"},\"image\":{\"@id\":\"https:\\\/\\\/argonneboisenergie.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c0\u00a0propos - Argonne Bois Energie","description":"le r\u00f4le d'Argonne Bois \u00c9nergie est de rechercher les espaces bois\u00e9s locaux \u00e0 entretenir dans un futur proche, r\u00e9pondre \u00e0 cette offre et les transformer en bordure de parcelles ou sur nos plateformes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/argonneboisenergie.com\/index.php\/a-propos\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c0\u00a0propos - Argonne Bois Energie","og_description":"le r\u00f4le d'Argonne Bois \u00c9nergie est de rechercher les espaces bois\u00e9s locaux \u00e0 entretenir dans un futur proche, r\u00e9pondre \u00e0 cette offre et les transformer en bordure de parcelles ou sur nos plateformes","og_url":"https:\/\/argonneboisenergie.com\/index.php\/a-propos\/","og_site_name":"Argonne Bois Energie","article_modified_time":"2024-08-01T10:30:20+00:00","og_image":[{"url":"https:\/\/argonneboisenergie.com\/wp-content\/uploads\/2024\/07\/biomasse-WD-ABE.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/argonneboisenergie.com\/index.php\/a-propos\/","url":"https:\/\/argonneboisenergie.com\/index.php\/a-propos\/","name":"\u00c0\u00a0propos - Argonne Bois Energie","isPartOf":{"@id":"https:\/\/argonneboisenergie.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/argonneboisenergie.com\/index.php\/a-propos\/#primaryimage"},"image":{"@id":"https:\/\/argonneboisenergie.com\/index.php\/a-propos\/#primaryimage"},"thumbnailUrl":"https:\/\/argonneboisenergie.com\/wp-content\/uploads\/2024\/07\/biomasse-WD-ABE.png","datePublished":"2024-07-16T14:16:48+00:00","dateModified":"2024-08-01T10:30:20+00:00","description":"le r\u00f4le d'Argonne Bois \u00c9nergie est de rechercher les espaces bois\u00e9s locaux \u00e0 entretenir dans un futur proche, r\u00e9pondre \u00e0 cette offre et les transformer en bordure de parcelles ou sur nos plateformes","breadcrumb":{"@id":"https:\/\/argonneboisenergie.com\/index.php\/a-propos\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/argonneboisenergie.com\/index.php\/a-propos\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/argonneboisenergie.com\/index.php\/a-propos\/#primaryimage","url":"https:\/\/argonneboisenergie.com\/wp-content\/uploads\/2024\/07\/biomasse-WD-ABE.png","contentUrl":"https:\/\/argonneboisenergie.com\/wp-content\/uploads\/2024\/07\/biomasse-WD-ABE.png","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/argonneboisenergie.com\/index.php\/a-propos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/argonneboisenergie.com\/"},{"@type":"ListItem","position":2,"name":"\u00c0\u00a0propos"}]},{"@type":"WebSite","@id":"https:\/\/argonneboisenergie.com\/#website","url":"https:\/\/argonneboisenergie.com\/","name":"Argonne Bois Energie","description":"LES SP\u00c9CIALISTES DU BOIS \u00c9NERGIE EN CIRCUIT COURT !","publisher":{"@id":"https:\/\/argonneboisenergie.com\/#organization"},"alternateName":"ABE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/argonneboisenergie.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/argonneboisenergie.com\/#organization","name":"Argonne Bois Energie","url":"https:\/\/argonneboisenergie.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/argonneboisenergie.com\/#\/schema\/logo\/image\/","url":"https:\/\/argonneboisenergie.com\/wp-content\/uploads\/2024\/05\/titre-ABE-2.png","contentUrl":"https:\/\/argonneboisenergie.com\/wp-content\/uploads\/2024\/05\/titre-ABE-2.png","width":250,"height":127,"caption":"Argonne Bois Energie"},"image":{"@id":"https:\/\/argonneboisenergie.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/argonneboisenergie.com\/index.php\/wp-json\/wp\/v2\/pages\/1315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/argonneboisenergie.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/argonneboisenergie.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/argonneboisenergie.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/argonneboisenergie.com\/index.php\/wp-json\/wp\/v2\/comments?post=1315"}],"version-history":[{"count":19,"href":"https:\/\/argonneboisenergie.com\/index.php\/wp-json\/wp\/v2\/pages\/1315\/revisions"}],"predecessor-version":[{"id":1482,"href":"https:\/\/argonneboisenergie.com\/index.php\/wp-json\/wp\/v2\/pages\/1315\/revisions\/1482"}],"wp:attachment":[{"href":"https:\/\/argonneboisenergie.com\/index.php\/wp-json\/wp\/v2\/media?parent=1315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}